{"id":17,"date":"2020-01-31T12:50:51","date_gmt":"2020-01-31T12:50:51","guid":{"rendered":"https:\/\/totnethome.com\/?page_id=17"},"modified":"2022-04-20T15:36:56","modified_gmt":"2022-04-20T15:36:56","slug":"aviso-legal","status":"publish","type":"page","link":"https:\/\/totnethome.com\/ca\/aviso-legal\/","title":{"rendered":"Aviso legal"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"17\" class=\"elementor elementor-17\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-455e278 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"455e278\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[{&quot;jet_parallax_layout_image&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;_id&quot;:&quot;113b64d&quot;,&quot;jet_parallax_layout_image_tablet&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_image_mobile&quot;:{&quot;url&quot;:&quot;&quot;,&quot;id&quot;:&quot;&quot;,&quot;size&quot;:&quot;&quot;},&quot;jet_parallax_layout_speed&quot;:{&quot;unit&quot;:&quot;%&quot;,&quot;size&quot;:50,&quot;sizes&quot;:[]},&quot;jet_parallax_layout_type&quot;:&quot;scroll&quot;,&quot;jet_parallax_layout_direction&quot;:&quot;1&quot;,&quot;jet_parallax_layout_fx_direction&quot;:null,&quot;jet_parallax_layout_z_index&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x&quot;:50,&quot;jet_parallax_layout_bg_x_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_x_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y&quot;:50,&quot;jet_parallax_layout_bg_y_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_y_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size&quot;:&quot;auto&quot;,&quot;jet_parallax_layout_bg_size_tablet&quot;:&quot;&quot;,&quot;jet_parallax_layout_bg_size_mobile&quot;:&quot;&quot;,&quot;jet_parallax_layout_animation_prop&quot;:&quot;transform&quot;,&quot;jet_parallax_layout_on&quot;:[&quot;desktop&quot;,&quot;tablet&quot;]}]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c6ce73e\" data-id=\"c6ce73e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-528891a elementor-widget elementor-widget-heading\" data-id=\"528891a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Aviso Legal y Condiciones de uso del portal<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-75ee995 elementor-widget elementor-widget-text-editor\" data-id=\"75ee995\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con el fin de dar cumplimiento al art\u00edculo 10 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, informamos a los usuarios de nuestros datos:<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-cc43bf0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cc43bf0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-928d6a6\" data-id=\"928d6a6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f49624 elementor-widget elementor-widget-text-editor\" data-id=\"7f49624\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"layoutArea\"><div class=\"column\"><p>Denominacio\u0301n Social:<strong> TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A.<\/strong><\/p><p>Domicilio Social: Ctra. de Montcada, 600, 08223, Terrassa, (Barcelona)<\/p><p>CIF: A08754335<br \/>Tele\u0301fono: 902360099<br \/>E-Mail: totnet@totnet.es<br \/>Sitio Web: https:\/\/www.totnethomes.es<br \/>Datos Registrales: Barcelona, Tomo 5112, Folio 50, Hoja 61587, Inscripcio\u0301n 1a<\/p><\/div><\/div><div class=\"layoutArea\"><div class=\"column\"><p>La actividad que desarrolla la empresa es la de limpieza y mantenimiento de locales y edificios.<\/p><p>El Horario de atencio\u0301n al pu\u0301blico, es el siguiente: visitas concertadas<\/p><p><strong>1.- OBJETO<\/strong><\/p><p><strong>TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A.<\/strong> (en adelante tambie\u0301n el prestador) como responsable del sitio web, pone a disposicio\u0301n de los usuarios el presente documento, que regula el uso del sitio web https:\/\/www.totnet.es, con el que pretendemos dar cumplimiento a las obligaciones que dispone la Ley 34\/2002, de Servicios de la Sociedad de la Informacio\u0301n y del Comercio Electro\u0301nico (LSSICE o LSSI), asi\u0301 como informar a todos los usuarios del sitio web respecto de cua\u0301les son las condiciones de uso del sitio web.<\/p><p>A trave\u0301s de la Web,<strong> TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A<\/strong>. facilita a los usuarios el acceso y utilizacio\u0301n de diferentes servicios y contenidos puestos a disposicio\u0301n a trave\u0301s del web.<\/p><p>Toda persona que acceda a esta web asume el papel de usuario (en adelante el usuario), e implica la aceptacio\u0301n total y sin reservas de todas y cada una de las disposiciones incluidas en este aviso legal, asi\u0301 como a cualesquiera otras disposiciones legales que fueran de aplicacio\u0301n.<\/p><div class=\"page\" title=\"Page 2\"><div class=\"layoutArea\"><div class=\"column\"><p>Como usuarios, tienen que leer atentamente este Aviso Legal en cualquier de las ocasiones que entren a la web, pues e\u0301sta puede sufrir modificaciones ya que el prestador se reserva el derecho a modificar cualquier tipo de informacio\u0301n que pudiera aparecer en la web, sin que exista la obligacio\u0301n de pre-avisar o poner en conocimiento de los usuarios estas obligaciones, siendo suficientes la publicacio\u0301n en el sitio web del prestador.<\/p><p><strong>2. CONDICIONES DE ACCESO I USO DE LA WEB.<\/strong><\/p><p><strong>2.1. Cara\u0301cter gratuito del acceso y uso de la web.<\/strong><\/p><p>La prestacio\u0301n de los servicios por parte de <strong>TOT-NET <\/strong><strong>\u00a0SERVICIOS DE LIMPIEZA GRUPO NETTO<\/strong>, S.A. tiene cara\u0301cter gratuito para todos los Usuarios. No obstante, algunos de los servicios suministrados por el prestador a trave\u0301s de la Web pueden estar sujetas al pago de un precio.<\/p><p><strong>2.2. Registro de Usuario.<\/strong><\/p><p>Con cara\u0301cter general la prestacio\u0301n de los Servicios exige la previa suscripcio\u0301n o registro de los Usuarios. Aun asi\u0301, <strong>TOT-NET <\/strong><strong>\u00a0SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A<\/strong>. condiciona el uso de algunos de los servicios a la previa complementacio\u0301n del correspondiente registro de Usuario. Este registro se efectuara\u0301 en la forma expresamente indicada en la propia seccio\u0301n del servicio.<\/p><p><strong>2.3. Veracidad de la informacio\u0301n.<\/strong><\/p><p>Toda la informacio\u0301n que facilita el Usuario tiene que ser veraz. A estos efectos, el Usuario garantiza la autenticidad de los datos comunicados a trave\u0301s de los formularios para la suscripcio\u0301n de los Servicios. Sera\u0301 responsabilidad del Usuario mantener toda la informacio\u0301n facilitada a <strong>TOT-NET <\/strong><strong>\u00a0SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A.<\/strong> permanentemente actualizada de forma que responda, en cada momento, a su situacio\u0301n real. En todo caso, el Usuario sera\u0301 el u\u0301nico responsable de las manifestaciones falsas o inexactas que realice y de los perjuicios que cause al prestador o a terceros.<\/p><div class=\"page\" title=\"Page 3\"><div class=\"layoutArea\"><div class=\"column\"><p><strong>2.4. Menores de edad.<\/strong><\/p><p>Para el uso de los servicios, los menores de edad tienen que obtener siempre previamente el consentimiento de los padres, tutores o representantes legales, responsables u\u0301ltimos de todos los actos realizados por los menores a su cargo. La responsabilidad en la determinacio\u0301n de contenidos concretos a los cuales acceden los menores corresponde a aquellos, es por eso que si acceden a contenidos no apropiados por Internet, se tendra\u0301n que establecer en sus ordenadores mecanismos, en particular programas informa\u0301ticos, filtros y bloqueos, que permitan limitar los contenidos disponibles y, a pesar de que no sean infalibles, son de especial utilidad para controlar y restringir los materiales a los que pueden acceder los menores.<\/p><p><strong>2.5. Obligacio\u0301n de hacer un uso correcto de la Web.<\/strong><\/p><p>El Usuario se compromete a utilizar la Web de conformidad a la Ley y al presente Aviso Legal, asi\u0301 como a la moral y a buenas costumbres. A tal efecto, el Usuario se abstendra\u0301 de utilizar la pa\u0301gina con finalidades ili\u0301citas o prohibidas, lesivas de derechos e intereses de terceros, o que de cualquier forma puedan dan\u0303ar, inutilizar, sobrecargar, deteriorar o impedir la normal utilizacio\u0301n de equipos informa\u0301ticos o documentos, archivos y toda clase de contenidos almacenados en cualquier equipo informa\u0301tico del prestador.<\/p><p>En particular, y a ti\u0301tulo indicativo pero no exhaustivo, el Usuario se compromete a no transmitir, difundir o poner a disposicio\u0301n de terceros informaciones, datos, contenidos, mensajes, gra\u0301ficos, dibujos, archivos de sonido o imagen, fotografi\u0301as, grabaciones, software y, en general, cualquier clase de material que:<\/p><div class=\"page\" title=\"Page 4\"><div class=\"layoutArea\"><div class=\"column\"><ol><li><p>sea contraria, desprecie o atente contra los derechos fundamentales y las libertades pu\u0301blicas reconocidas constitucionalmente, en tratados internacionales y otras normas vigentes;<\/p><\/li><li><p>induzca, incite o promueva actuaciones delictivas, denigrantes, difamatorias, violentas o, en general, contrarias a la ley, a la moral y al orden pu\u0301blico;<\/p><\/li><\/ol><p>c.induzca, incite o promueva actuaciones, actitudes o pensamientos discriminatorios por razo\u0301n de sexo, raza, religio\u0301n, creencias, edad o condicio\u0301n;<\/p><ol start=\"4\"><li><p>sea contrario al derecho al honor, a la intimidad personal o familiar o a la propia imagen de las personas;<\/p><\/li><li><p>de cualquier manera perjudique la credibilidad del prestador o de terceros; y<\/p><\/li><li><p>constituya publicidad ili\u0301cita, engan\u0303osa o desleal.<\/p><\/li><\/ol><p><strong>3.- EXCLUSIO\u0301N DE GARANTI\u0301AS Y RESPONSABILIDAD<\/strong><\/p><p>El prestador se exime de cualquier tipo de responsabilidad derivada de la informacio\u0301n publicada en nuestro sitio web, siempre que esta informacio\u0301n haya sido manipulada o introducida por un tercero.<\/p><p>Esta web ha sido revisada y probada para que funcione correctamente. En principio, se puede garantizar el correcto funcionamiento los 365 di\u0301as del an\u0303o, 24 horas al di\u0301a. Sin embargo, el prestador no descarta la posibilidad que existan determinados errores de programacio\u0301n, o que sucedan causas de fuerza mayor, cata\u0301strofes naturales, huelgas, o circunstancias parecidas que hagan imposible el acceso a la pa\u0301gina web.<\/p><p><strong>TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A<\/strong>. no otorga ninguna garanti\u0301a ni se hace responsable, en ningu\u0301n caso, de los dan\u0303os y perjuicios de cualquier naturaleza que puedan salir a colacio\u0301n de la falta de disponibilidad, mantenimiento y efectivo funcionamiento de la web o de sus servicios y contenidos; de la existencia de virus, programas maliciosos o lesivos en los contenidos; del uso ili\u0301cito, negligente, fraudulento o contrario a este Aviso Legal y condiciones de uso; o de La falta de licitud, calidad, fiabilidad, utilidad y disponibilidad de los servicios prestados por terceros y ademanes a disposicio\u0301n de los usuarios en el sitio web.<\/p><p>El prestador no se hace responsable bajo ningu\u0301n concepto de los dan\u0303os que puedan dimanar del uso ilegal o indebido de la presente pa\u0301gina web.<\/p><p><strong>4.- COOKIES<\/strong><\/p><p>El sitio web del prestador puede utilizar cookies (pequen\u0303os archivos de informacio\u0301n que el servidor envi\u0301a al ordenador de quien accede en la pa\u0301gina) para llevar a cabo determinadas funciones que son consideradas imprescindibles para el correcto funcionamiento y visualizacio\u0301n del lugar. Las cookies utilizadas tienen, en todo caso, cara\u0301cter temporal, con la u\u0301nica finalidad de hacer ma\u0301s eficaz la navegacio\u0301n, y desaparecen al acabar la sesio\u0301n del usuario.<\/p><\/div><\/div><\/div><div class=\"page\" title=\"Page 5\"><div class=\"layoutArea\"><div class=\"column\"><p>Para ma\u0301s informacio\u0301n, ver nuestra <a href=\"https:\/\/totnet.es\/politica-de-cookies\/\">Poli\u0301tica de Cookies<\/a>.\u00a0<\/p><p><strong>5.- ENLACES (LINKS)<\/strong><\/p><p>Desde el sitio web es posible que se redirija a contenidos de terceras webs. Dado que desde el web no podemos controlar siempre los contenidos introducidos por los terceros, <strong>TOT-NET <\/strong><strong>\u00a0SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A<\/strong>. no asume ningu\u0301n tipo de responsabilidad respecto a estos contenidos. En todo caso, el prestador manifiesta que procedera\u0301 a la retirada inmediata de cualquier contenido que pudiera contravenir la legislacio\u0301n nacional o internacional, la moral o el orden pu\u0301blico, procediendo a la retirada inmediata de la re-direccio\u0301n a estas webs, poniendo en conocimiento de las autoridades competentes el contenido en cuestio\u0301n.<\/p><p>El prestador no se responsabiliza de la informacio\u0301n y contenidos almacenados, a ti\u0301tulo enunciativo pero no limitante, en foros, chats, generadores de blogs, comentarios, redes sociales o cualquiera otro medio que permita a terceros publicar contenidos de forma independiente a la pa\u0301gina web del prestador. Sin embargo y en cumplimiento de lo que dispone el art. 11 y 16 de la LSSICE, el prestador se pone a disposicio\u0301n de todos los usuarios, autoridades y fuerzas de seguridad, y colaborando de forma activa en la retirada o, cuando sea necesario, el bloqueo de todos aquellos contenidos que puedan afectar o contravenir la legislacio\u0301n nacional, o internacional, derechos de terceros o la moral y el orden pu\u0301blico. En caso de que el usuario considere que puede existir algu\u0301n contenido que pudiera ser susceptible de esta clasificacio\u0301n, se ruega lo notifique de forma inmediata al administrador del sitio web.<\/p><p><strong>6.- PROTECCIO\u0301N DE DATOS PERSONALES<\/strong><\/p><p>El prestador esta\u0301 comprometido con el cumplimiento de la normativa de proteccio\u0301n de datos personales y garantiza el cumplimiento i\u0301ntegro de las obligaciones dispuestas, asi\u0301 como la implementacio\u0301n de las medidas de seguridad dispuestas al Reglamento Europeo de Proteccio\u0301n de datos y la normativa espan\u0303ola de proteccio\u0301n de datos. Para ma\u0301s informacio\u0301n, ver nuestra <a href=\"https:\/\/totnet.es\/politica-de-privacidad-de-tot-net\/\">Poli\u0301tica de Privacidad<\/a>.\u00a0<\/p><\/div><\/div><\/div><div class=\"page\" title=\"Page 6\"><div class=\"layoutArea\"><div class=\"column\"><p><strong>7.- PROPIEDAD INTELECTUAL E INDUSTRIAL<\/strong><\/p><p>El sitio web, incluyendo a ti\u0301tulo enunciativo pero no limitativo la programacio\u0301n, edicio\u0301n, compilacio\u0301n y otros elementos necesarios para su funcionamiento, los disen\u0303os, logotipos, textos, fotografi\u0301as y\/o gra\u0301ficos son propiedad del prestador o, en caso de que fuera necesario, dispone de la licencia o autorizacio\u0301n expresa por parte de los autores. Todos los contenidos del sitio web se encuentran debidamente protegidos por la normativa de propiedad intelectual e industrial.<\/p><p>Independientemente de la finalidad por la que fueran destinados, la reproduccio\u0301n total o parcial, uso, distribucio\u0301n y comunicacio\u0301n pu\u0301blica requieren de la autorizacio\u0301n escrita previa por parte del prestador. Cualquier uso no autorizado previamente por parte del prestador sera\u0301 considerado un incumplimiento grave de los derechos de propiedad intelectual o industrial del autor.<\/p><p>Los disen\u0303os, logotipos, textos y\/o gra\u0301ficos ajenos al prestador y que puedan aparecer en el sitio web, pertenecen a sus respectivos propietarios, siendo ellos mismos los responsables de cualquier posible controversia que pudiera acontecer respecto a los mismos. En todo caso, el prestador cuenta con la autorizacio\u0301n expresa y previa por parte de los mismos.<\/p><p>El prestador reconoce a favor de sus titulares los correspondientes derechos de propiedad industrial e intelectual, no implicando la mencio\u0301n o aparicio\u0301n en el sitio web, de la existencia de derechos o ninguna responsabilidad del prestador sobre los mismos, como tampoco respaldo, patrocinio o recomendacio\u0301n por parte del mismo.<\/p><p>Para realizar cualquier tipo de observacio\u0301n respecto a posibles incumplimientos de los derechos de propiedad intelectual o industrial, asi\u0301 como sobre cualquiera de los contenidos del sitio web, puede hacerlo a trave\u0301s del correo electro\u0301nico arriba resen\u0303ado.<\/p><p><strong>8.- LEY APLICABLE Y JURISDICCIO\u0301N<\/strong><\/p><p>Para la resolucio\u0301n de las controversias o cuestiones relacionadas con la presente pa\u0301gina web o de las actividades en esta desarrolladas, sera\u0301 de aplicacio\u0301n la legislacio\u0301n espan\u0303ola, a la que se someten expresamente las partes, siendo competentes por la resolucio\u0301n de todos los conflictos derivados o relacionados con su uso los Juzgados y Tribunales de Barcelona.<\/p><\/div><\/div><\/div><div class=\"page\" title=\"Page 7\"><div class=\"layoutArea\"><div class=\"column\"><p>U\u0301ltima actualizacio\u0301n: 30 Septiembre 2021<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Aviso Legal y Condiciones de uso del portal Con el fin de dar cumplimiento al art\u00edculo 10 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, informamos a los usuarios de nuestros datos: Denominacio\u0301n Social: TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A. Domicilio Social: Ctra. de Montcada, 600, [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v26.3 (Yoast SEO v27.9) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Aviso legal - Tot-Net Homes<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/totnethome.com\/ca\/aviso-legal\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aviso legal\" \/>\n<meta property=\"og:description\" content=\"Aviso Legal y Condiciones de uso del portal Con el fin de dar cumplimiento al art\u00edculo 10 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, informamos a los usuarios de nuestros datos: Denominacio\u0301n Social: TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A. Domicilio Social: Ctra. de Montcada, 600, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/totnethome.com\/ca\/aviso-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"Tot-Net Homes\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-20T15:36:56+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"9 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/aviso-legal\\\/\",\"url\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/aviso-legal\\\/\",\"name\":\"Aviso legal - Tot-Net Homes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#website\"},\"datePublished\":\"2020-01-31T12:50:51+00:00\",\"dateModified\":\"2022-04-20T15:36:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/aviso-legal\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/totnethome.com\\\/ca\\\/aviso-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/aviso-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aviso legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/\",\"name\":\"Tot-Net Homes\",\"description\":\"TOT NET HOME, es la l\u00ednea dedicada a los servicios de limpieza en comunidades de vecinos, oficinas, comercios y domicilios particulares\",\"publisher\":{\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#organization\",\"name\":\"Tot-Net Homes\",\"url\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Logo-Tot-Net-Home.jpg\",\"contentUrl\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/07\\\/Logo-Tot-Net-Home.jpg\",\"width\":900,\"height\":526,\"caption\":\"Tot-Net Homes\"},\"image\":{\"@id\":\"https:\\\/\\\/totnethome.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Aviso legal - Tot-Net Homes","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/totnethome.com\/ca\/aviso-legal\/","og_locale":"ca_ES","og_type":"article","og_title":"Aviso legal","og_description":"Aviso Legal y Condiciones de uso del portal Con el fin de dar cumplimiento al art\u00edculo 10 de la Ley 34\/2002 de Servicios de la Sociedad de la Informaci\u00f3n y del Comercio Electr\u00f3nico, informamos a los usuarios de nuestros datos: Denominacio\u0301n Social: TOT-NET SERVICIOS DE LIMPIEZA GRUPO NETTO, S.A. Domicilio Social: Ctra. de Montcada, 600, [&hellip;]","og_url":"https:\/\/totnethome.com\/ca\/aviso-legal\/","og_site_name":"Tot-Net Homes","article_modified_time":"2022-04-20T15:36:56+00:00","twitter_card":"summary_large_image","twitter_misc":{"Temps estimat de lectura":"9 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/totnethome.com\/ca\/aviso-legal\/","url":"https:\/\/totnethome.com\/ca\/aviso-legal\/","name":"Aviso legal - Tot-Net Homes","isPartOf":{"@id":"https:\/\/totnethome.com\/ca\/#website"},"datePublished":"2020-01-31T12:50:51+00:00","dateModified":"2022-04-20T15:36:56+00:00","breadcrumb":{"@id":"https:\/\/totnethome.com\/ca\/aviso-legal\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/totnethome.com\/ca\/aviso-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/totnethome.com\/ca\/aviso-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/totnethome.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Aviso legal"}]},{"@type":"WebSite","@id":"https:\/\/totnethome.com\/ca\/#website","url":"https:\/\/totnethome.com\/ca\/","name":"Tot-Net Homes","description":"TOT NET HOME, es la l\u00ednea dedicada a los servicios de limpieza en comunidades de vecinos, oficinas, comercios y domicilios particulares","publisher":{"@id":"https:\/\/totnethome.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/totnethome.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/totnethome.com\/ca\/#organization","name":"Tot-Net Homes","url":"https:\/\/totnethome.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/totnethome.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/totnethome.com\/ca\/wp-content\/uploads\/sites\/2\/2020\/07\/Logo-Tot-Net-Home.jpg","contentUrl":"https:\/\/totnethome.com\/ca\/wp-content\/uploads\/sites\/2\/2020\/07\/Logo-Tot-Net-Home.jpg","width":900,"height":526,"caption":"Tot-Net Homes"},"image":{"@id":"https:\/\/totnethome.com\/ca\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/pages\/17","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/comments?post=17"}],"version-history":[{"count":5,"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/pages\/17\/revisions"}],"predecessor-version":[{"id":9060,"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/pages\/17\/revisions\/9060"}],"wp:attachment":[{"href":"https:\/\/totnethome.com\/ca\/wp-json\/wp\/v2\/media?parent=17"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}